{"id":35,"count":1,"description":"","link":"https:\/\/qizew.com\/de\/category\/android\/","name":"Android","slug":"android","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/qizew.com\/de\/wp-json\/wp\/v2\/categories\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qizew.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/qizew.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/qizew.com\/de\/wp-json\/wp\/v2\/posts?categories=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}