{"id":407,"date":"2025-03-24T05:20:05","date_gmt":"2025-03-24T05:20:05","guid":{"rendered":"https:\/\/mobzla.com\/?page_id=407"},"modified":"2026-02-10T00:55:18","modified_gmt":"2026-02-10T00:55:18","slug":"termos-de-uso","status":"publish","type":"page","link":"https:\/\/qizew.com\/lt\/termos-de-uso\/","title":{"rendered":"Termos de Uso"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Termos de Uso do Qizew<\/h2>\n<p>Ao acessar ao site Qizew, concorda em cumprir estes termos de servi\u00e7o, todas as leis e regulamentos aplic\u00e1veis e concorda que \u00e9 respons\u00e1vel pelo cumprimento de todas as leis locais aplic\u00e1veis. Se voc\u00ea n\u00e3o concordar com algum desses termos, est\u00e1 proibido de usar ou acessar este site. Os materiais contidos neste site s\u00e3o protegidos pelas leis de direitos autorais e marcas comerciais aplic\u00e1veis.<\/p>\n<h2 class=\"wp-block-heading\">Uso de Licen\u00e7a<\/h2>\n<p>\u00c9 concedida permiss\u00e3o para baixar temporariamente uma c\u00f3pia dos materiais (informa\u00e7\u00f5es ou software) no site Qizew, apenas para visualiza\u00e7\u00e3o transit\u00f3ria pessoal e n\u00e3o comercial. Esta \u00e9 a concess\u00e3o de uma licen\u00e7a, n\u00e3o uma transfer\u00eancia de t\u00edtulo e, sob esta licen\u00e7a, voc\u00ea n\u00e3o pode:<\/p>\n<ul class=\"wp-block-list\">\n<li>modificar ou copiar os materiais;<\/li>\n<li>usar os materiais para qualquer finalidade comercial ou para exibi\u00e7\u00e3o p\u00fablica (comercial ou n\u00e3o comercial);<\/li>\n<li>tentar descompilar ou fazer engenharia reversa de qualquer software contido no site Qizew;<\/li>\n<li>remover quaisquer direitos autorais ou outras nota\u00e7\u00f5es de propriedade dos materiais; ou<\/li>\n<li>transferir os materiais para outra pessoa ou \u2018espelhe\u2019 os materiais em qualquer outro servidor. Esta licen\u00e7a ser\u00e1 automaticamente rescindida se voc\u00ea violar alguma dessas restri\u00e7\u00f5es e poder\u00e1 ser rescindida por Qizew a qualquer momento. Ao encerrar a visualiza\u00e7\u00e3o desses materiais ou ap\u00f3s o t\u00e9rmino desta licen\u00e7a, voc\u00ea deve apagar todos os materiais baixados em sua posse, seja em formato eletr\u00f3nico ou impresso.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\">Isen\u00e7\u00e3o de responsabilidade<\/h2>\n<p>Os materiais no site da Qizew s\u00e3o fornecidos \u2018como est\u00e3o\u2019. Qizew n\u00e3o oferece garantias, expressas ou impl\u00edcitas, e, por este meio, isenta e nega todas as outras garantias, incluindo, sem limita\u00e7\u00e3o, garantias impl\u00edcitas ou condi\u00e7\u00f5es de comercializa\u00e7\u00e3o, adequa\u00e7\u00e3o a um fim espec\u00edfico ou n\u00e3o viola\u00e7\u00e3o de propriedade intelectual ou outra viola\u00e7\u00e3o de direitos.<\/p>\n<p>Al\u00e9m disso, o Qizew n\u00e3o garante ou faz qualquer representa\u00e7\u00e3o relativa \u00e0 precis\u00e3o, aos resultados prov\u00e1veis ou \u00e0 confiabilidade do uso dos materiais em seu site ou de outra forma relacionado a esses materiais ou em sites vinculados a este site.<\/p>\n<h2 class=\"wp-block-heading\">Limita\u00e7\u00f5es<\/h2>\n<p>Em nenhum caso o Qizew ou seus fornecedores ser\u00e3o respons\u00e1veis por quaisquer danos (incluindo, sem limita\u00e7\u00e3o, danos por perda de dados ou lucro ou devido a interrup\u00e7\u00e3o dos neg\u00f3cios) decorrentes do uso ou da incapacidade de usar os materiais em Qizew, mesmo que Qizew ou um representante autorizado do Qizew tenha sido notificado oralmente ou por escrito da possibilidade de tais danos. Como algumas jurisdi\u00e7\u00f5es n\u00e3o permitem limita\u00e7\u00f5es em garantias impl\u00edcitas, ou limita\u00e7\u00f5es de responsabilidade por danos conseq\u00fcentes ou incidentais, essas limita\u00e7\u00f5es podem n\u00e3o se aplicar a voc\u00ea.<\/p>\n<h2 class=\"wp-block-heading\">Precis\u00e3o dos materiais<\/h2>\n<p>Os materiais exibidos no site do Qizew podem incluir erros t\u00e9cnicos, tipogr\u00e1ficos ou fotogr\u00e1ficos. Qizew n\u00e3o garante que qualquer material em seu site seja preciso, completo ou atual. Qizew pode fazer altera\u00e7\u00f5es nos materiais contidos em seu site a qualquer momento, sem aviso pr\u00e9vio. No entanto, Qizew n\u00e3o se compromete a atualizar os materiais.<\/p>\n<h2 class=\"wp-block-heading\">Links<\/h2>\n<p>O Qizew n\u00e3o analisou todos os sites vinculados ao seu site e n\u00e3o \u00e9 respons\u00e1vel pelo conte\u00fado de nenhum site vinculado. A inclus\u00e3o de qualquer link n\u00e3o implica endosso por Qizew do site. O uso de qualquer site vinculado \u00e9 por conta e risco do usu\u00e1rio.<\/p>\n<h2 class=\"wp-block-heading\">Modifica\u00e7\u00f5es<\/h2>\n<p>O Qizew pode revisar estes termos de servi\u00e7o do site a qualquer momento, sem aviso pr\u00e9vio. Ao usar este site, voc\u00ea concorda em ficar vinculado \u00e0 vers\u00e3o atual desses termos de servi\u00e7o.<\/p>\n<p>Lei aplic\u00e1vel Estes termos e condi\u00e7\u00f5es s\u00e3o regidos e interpretados de acordo com as leis do Qizew e voc\u00ea se submete irrevogavelmente \u00e0 jurisdi\u00e7\u00e3o exclusiva dos tribunais naquele estado ou localidade.<\/p>\n<h2 id=\"lei-aplicavel\" class=\"wp-block-heading\">Lei aplic\u00e1vel<\/h2>\n<p>Estes termos e condi\u00e7\u00f5es s\u00e3o regidos e interpretados de acordo com as leis do Qizew e voc\u00ea se submete irrevogavelmente \u00e0 jurisdi\u00e7\u00e3o exclusiva dos tribunais naquele estado ou localidade.<\/p>","protected":false},"excerpt":{"rendered":"<p>Termos de Uso do Qizew Ao acessar ao site Qizew, concorda em cumprir estes termos de servi\u00e7o, todas as leis e regulamentos aplic\u00e1veis e concorda que \u00e9 respons\u00e1vel pelo cumprimento de todas as leis locais aplic\u00e1veis. Se voc\u00ea n\u00e3o concordar com algum desses termos, est\u00e1 proibido de usar ou acessar este site. Os materiais contidos [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-407","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/pages\/407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/comments?post=407"}],"version-history":[{"count":5,"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/pages\/407\/revisions"}],"predecessor-version":[{"id":6016,"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/pages\/407\/revisions\/6016"}],"wp:attachment":[{"href":"https:\/\/qizew.com\/lt\/wp-json\/wp\/v2\/media?parent=407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}