{"id":208,"date":"2022-04-16T10:40:29","date_gmt":"2022-04-16T10:40:29","guid":{"rendered":"http:\/\/lerartigos.com\/?p=208"},"modified":"2026-02-10T00:51:47","modified_gmt":"2026-02-10T00:51:47","slug":"saiba-como-solicitar-a-carteira-de-motorista-de-graca","status":"publish","type":"post","link":"https:\/\/qizew.com\/ru\/saiba-como-solicitar-a-carteira-de-motorista-de-graca\/","title":{"rendered":"Saiba como solicitar a carteira de motorista de gra\u00e7a"},"content":{"rendered":"<p>Voc\u00ea sabia que agora as pessoas podem tirar a carteira de motorista de gra\u00e7a? Afinal, dirigir \u00e9 um dos maiores sonhos da maioria dos brasileiros.&nbsp;<\/p>\n\n\n\n<p>Muitas pessoas sonham em saber dirigir para poder realizar o sonho de ter um carro pr\u00f3prio, outras querem dirigir para ter liberdade e facilidade no dia a dia.&nbsp;<\/p>\n\n\n\n<p>N\u00e3o importa o motivo de cada um, sempre h\u00e1 uma preocupa\u00e7\u00e3o em torno do assunto. Existem pessoas que n\u00e3o podem pagar pela<strong> Carteira Nacional de Habilita\u00e7\u00e3o (CNH)<\/strong> por serem bastante caras.&nbsp;<\/p>\n\n\n\n<p>Por\u00e9m, agora existe a possibilidade de emitir a carteira de motorista de gra\u00e7a. Deseja saber como funciona? Ent\u00e3o leia at\u00e9 o final!&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Saiba como funciona o programa que disponibiliza a carteira de motorista de gra\u00e7a&nbsp;<\/strong><\/h2>\n\n\n\n<p>Os brasileiros que possuem renda baixa podem recorrer ao direito de solicitar a carteira de motorista de gra\u00e7a.&nbsp;<\/p>\n\n\n\n<p>O programa <strong>CNH Socia<\/strong>l foi criado em<strong> 2011<\/strong> pelo <strong>Governo Federal <\/strong>com o objetivo de melhorar as oportunidades de trabalho das pessoas.&nbsp;<\/p>\n\n\n\n<p>Pois existem muitas empresas que precisam de motoristas particulares e motoristas comerciais para realizarem trabalhos de entrega.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, ter a carteira de motorista tamb\u00e9m pode ser um grande diferencial no momento de uma entrevista.&nbsp;<\/p>\n\n\n\n<p>Pois entendemos que uma pessoa que dirige j\u00e1 passou pela etapa de auto-escola e exames do<strong> Detran.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como participar do programa CNH Social&nbsp;<\/strong><\/h2>\n\n\n\n<p>A participa\u00e7\u00e3o ocorre por meio de<strong> processo seletivo<\/strong> dentro dos Estados participantes do programa. Sendo assim, existem algumas caracter\u00edsticas \u00fanicas em cada lugar.&nbsp;<\/p>\n\n\n\n<p>A forma de inscri\u00e7\u00e3o atualmente ocorre de forma inteiramente online, sendo assim \u00e9 preciso acessar o<strong> <a href=\"https:\/\/www.detran.sp.gov.br\/wps\/portal\/portaldetran\/cidadao\/home\/!ut\/p\/z1\/jdBdi4JQEAbgX-Ot8-qROHZ3-tK1Fbdi085NWNhRUE-orX-_aGNhoaS5m-F5Z2BIUkKyTn8KlXaFrtPy1u_kaB-sMPV9bn9Ga8_FioeRZ29sIGQU3wFelADJd_IDQA6vj0neCXOwcSeWAJ9vFxB8zRbWPLKxxAP8nfCs2RTCdZzwI1gyuOwBBo4EJFWpD7__EPWBcUWyyU5ZkzXmpbmN8647t2MDBvq-N5XWqszMo64MPIvkuu0o-S_pXH0nKL6qmLfiCmRqh2E!\/dz\/d5\/L2dBISEvZ0FBIS9nQSEh\/\">site do Detran<\/a><\/strong> do seu estado.&nbsp;<\/p>\n\n\n\n<p>Na qual o candidato deve fornecer seus dados pessoais e realizar o preenchimento de um formul\u00e1rio para ser analisado.&nbsp;<\/p>\n\n\n\n<p><strong>Importante<\/strong>: fa\u00e7a o preenchimento de forma detalhada, disponibilize todas as informa\u00e7\u00f5es relevantes sobre voc\u00ea para que o selecionador possa de fato entender quem est\u00e1 fazendo o pedido de carteira de motorista de gra\u00e7a.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Regras para participar do programa<\/strong><\/h2>\n\n\n\n<p>Para participar do programa \u00e9 necess\u00e1rio atender alguns requisitos, como:&nbsp;<\/p>\n\n\n\n<p>\u2013 Ser maior de 18 anos de idade;<\/p>\n\n\n\n<p>\u2013 Receber at\u00e9 2 sal\u00e1rios m\u00ednimos;<\/p>\n\n\n\n<p>\u2013 Estudar ou ter estudado em rede p\u00fablica de ensino;<\/p>\n\n\n\n<p>\u2013 Ser do grupo de pessoas que recebem bolsa fam\u00edlia.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Os documentos necess\u00e1rios s\u00e3o:&nbsp;<\/strong><\/h2>\n\n\n\n<p>\u2013 Hist\u00f3rico escolar para as pessoas que forem estudantes;<\/p>\n\n\n\n<p>\u2013 Certifica\u00e7\u00e3o de conclus\u00e3o de curso do ensino m\u00e9dico para as pessoas que j\u00e1 tiverem terminado;<\/p>\n\n\n\n<p>\u2013 RG;<\/p>\n\n\n\n<p>\u2013 CPF<\/p>\n\n\n\n<p>\u2013 Comprovante de resid\u00eancia;&nbsp;<\/p>\n\n\n\n<p>\u2013 Carteira de trabalho dos familiares que residem na casa.<\/p>\n\n\n\n<p>Ap\u00f3s efetuar a inscri\u00e7\u00e3o, ser\u00e1 realizada a an\u00e1lise do cadastro do candidato.&nbsp;<\/p>\n\n\n\n<p>Se for selecionado, a pessoa deve ficar atenta aos pr\u00f3ximos passos que consistem nas diretrizes do Detran.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"330\" src=\"http:\/\/qizew.com\/wp-content\/uploads\/2022\/04\/cnh-de-graca.jpg-1.webp\" alt=\"\" class=\"wp-image-821\" srcset=\"https:\/\/qizew.com\/wp-content\/uploads\/2022\/04\/cnh-de-graca.jpg-1.webp 550w, https:\/\/qizew.com\/wp-content\/uploads\/2022\/04\/cnh-de-graca.jpg-1-300x180.webp 300w, https:\/\/qizew.com\/wp-content\/uploads\/2022\/04\/cnh-de-graca.jpg-1-18x12.webp 18w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>Processo de emiss\u00e3o da CNH<\/strong><\/h2>\n\n\n\n<p><strong>Existe um processo para emitir a CNH, como:<\/strong><\/p>\n\n\n\n<p>\u2013 Teste psicol\u00f3gico;<\/p>\n\n\n\n<p>\u2013 Matr\u00edcula na auto escola;<\/p>\n\n\n\n<p>\u2013 Teste te\u00f3rico;<\/p>\n\n\n\n<p>\u2013 Aulas pr\u00e1ticas;<\/p>\n\n\n\n<p>\u2013 Teste pr\u00e1tico.&nbsp;<\/p>\n\n\n\n<p>Todas essas etapas ser\u00e3o disponibilizadas atrav\u00e9s do<strong> Governo<\/strong> para que as pessoas possam ter capacita\u00e7\u00e3o para emitir a <strong>CNH Social.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Estados participantes do programa<\/strong><\/h2>\n\n\n\n<p>S\u00e3o Paulo;<\/p>\n\n\n\n<p>Minas Gerais;<\/p>\n\n\n\n<p>Roraima;<\/p>\n\n\n\n<p>Esp\u00edrito Santo;<\/p>\n\n\n\n<p>Bahia;<\/p>\n\n\n\n<p>Amazonas;<\/p>\n\n\n\n<p>Maranh\u00e3o;<\/p>\n\n\n\n<p>Cear\u00e1;<\/p>\n\n\n\n<p>Para\u00edba;<\/p>\n\n\n\n<p>Pernambuco;<\/p>\n\n\n\n<p>Rio Grande do Sul;<\/p>\n\n\n\n<p>Rio Grande do Norte;<\/p>\n\n\n\n<p>Distrito Federal;<\/p>\n\n\n\n<p>Goi\u00e1s.<\/p>\n\n\n\n<p>Sabendo disso, \u00e9 importante ficar atento para poder participar e n\u00e3o perder nenhum prazo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que agora as pessoas podem tirar a carteira de motorista de gra\u00e7a? Afinal, dirigir \u00e9 um dos maiores sonhos da maioria dos brasileiros.&nbsp; Muitas pessoas sonham em saber dirigir para poder realizar o sonho de ter um carro pr\u00f3prio, outras querem dirigir para ter liberdade e facilidade no dia a dia.&nbsp; N\u00e3o importa [&hellip;]<\/p>","protected":false},"author":1,"featured_media":821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[92,98,101,129,170,175],"class_list":{"0":"post-208","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-outros","8":"tag-carteira-de-motorista","9":"tag-cnh","10":"tag-cnh-social","11":"tag-detran","12":"tag-governo-federal","13":"tag-habilitacao"},"_links":{"self":[{"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/posts\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/comments?post=208"}],"version-history":[{"count":1,"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/posts\/208\/revisions"}],"predecessor-version":[{"id":5990,"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/posts\/208\/revisions\/5990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/media\/821"}],"wp:attachment":[{"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/media?parent=208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/categories?post=208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qizew.com\/ru\/wp-json\/wp\/v2\/tags?post=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}